{"id":8194,"date":"2016-12-26T09:00:26","date_gmt":"2016-12-26T09:00:26","guid":{"rendered":"http:\/\/localhost\/sdi\/www\/en-ae\/sds\/"},"modified":"2023-12-12T14:26:16","modified_gmt":"2023-12-12T03:26:16","slug":"sds","status":"publish","type":"page","link":"https:\/\/www.sdi.com.au\/en-ae\/downloads\/sds\/","title":{"rendered":"SDS"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_row_inner el_class=&#8221;no-padding&#8221;][vc_column_inner width=&#8221;2\/3&#8243;][vc_column_text]<\/p>\n<h1>Safety data sheets<\/h1>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner el_class=&#8221;download_item&#8221;][vc_column_inner][vc_column_text]<div class=\"pdf-download-list\">\n            <div class=\"pdf-download-items-row \" >\n                <div class=\"vc_row  \" >\n        \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/aura bulk fill_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/aura bulk fill.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>aura bulk fill<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/aura easy_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/aura easy.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>aura easy<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/aura easyflow_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/aura easyflow.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>aura easyflow<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/bonding resin_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/bonding resin.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>bonding resin<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/conseal f_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/conseal f.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>conseal f<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/eva tray material_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/eva tray material.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>eva tray material<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/gingival barrier_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/gingival barrier.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>gingival barrier<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/gs-80_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/gs-80.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>gs-80<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/lojic+_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/lojic+.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>lojic+<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/luna 2_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <i class=\"fa fa-file-pdf-o\" aria-hidden=\"true\"><\/i>\n                                                <span>luna 2<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/luna flow_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <i class=\"fa fa-file-pdf-o\" aria-hidden=\"true\"><\/i>\n                                                <span>luna flow<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/luna_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/luna.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>luna<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/permite_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/permite.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>permite<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/pola day 6 hp_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/pola day 6 hp.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>pola day 6 hp<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/pola day 7.5 hp_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/pola day 7.5 hp.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>pola day 7.5 hp<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/pola day 9.5 hp_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/pola day 9.5 hp.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>pola day 9.5 hp<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/pola day cp_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/pola day cp.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>pola day cp<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/pola luminate_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/pola luminate.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>pola luminate<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/pola night 10 cp_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/pola night 10 cp.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>pola night 10 cp<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/pola night 16 cp_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/pola night 16 cp.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>pola night 16 cp<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n                        <\/div>\n            <\/div>\n        \n                        <div class=\"pdf-download-items-row \" >\n                <div class=\"vc_row  \" >\n        \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/pola night 18 cp_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/pola night 18 cp.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>pola night 18 cp<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/pola night 22 cp_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/pola night 22 cp.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>pola night 22 cp<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/pola office liquid_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/pola office liquid.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>pola office liquid<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/pola office plus 37.5 hp_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/pola office plus 37.5 hp.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>pola office plus 37.5 hp<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/pola office powder_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/pola office powder.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>pola office powder<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/pola rapid 38 hp_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/pola rapid 38 hp.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>pola rapid 38 hp<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/pola rapid 6 hp_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/pola rapid 6 hp.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>pola rapid 6 hp<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/polishing paste_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/polishing paste.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>polishing paste<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/riva applicator pro_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/riva applicator pro.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>riva applicator pro<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/riva bond lc capsule_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/riva bond lc capsule.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>riva bond lc capsule<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/riva cem automix_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/riva cem automix.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>riva cem automix<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/riva coat_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/riva coat.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>riva coat<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/riva conditioner_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/riva conditioner.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>riva conditioner<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/riva light cure hv liquid_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/riva light cure hv liquid.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>riva light cure hv liquid<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/riva light cure hv powder_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/riva light cure hv powder.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>riva light cure hv powder<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/riva light cure liquid_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/riva light cure liquid.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>riva light cure liquid<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/riva light cure powder_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/riva light cure powder.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>riva light cure powder<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/riva luting capsules_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/riva luting capsules.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>riva luting capsules<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/riva luting liquid_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/riva luting liquid.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>riva luting liquid<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/riva luting plus capsules_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/riva luting plus capsules.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>riva luting plus capsules<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n                        <\/div>\n            <\/div>\n        \n                        <div class=\"pdf-download-items-row \" >\n                <div class=\"vc_row  \" >\n        \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/riva luting plus liquid_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/riva luting plus liquid.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>riva luting plus liquid<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/riva luting plus powder_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/riva luting plus powder.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>riva luting plus powder<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/riva luting powder_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/riva luting powder.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>riva luting powder<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/riva protect capsules_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/riva protect capsules.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>riva protect capsules<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/riva self cure capsules_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/riva self cure capsules.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>riva self cure capsules<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/riva self cure hv capsules_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/riva self cure hv capsules.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>riva self cure hv capsules<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/riva self cure liquid_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/riva self cure liquid.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>riva self cure liquid<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/riva self cure powder_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/riva self cure powder.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>riva self cure powder<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/riva silver capsules_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/riva silver capsules.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>riva silver capsules<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/riva silver liquid_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/riva silver liquid.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>riva silver liquid<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/riva silver powder_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/riva silver powder.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>riva silver powder<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/set pp and set_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/set pp and set.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>set pp and set<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/set pp base paste_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/set pp base paste.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>set pp base paste<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/set pp catalyst paste_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/set pp catalyst paste.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>set pp catalyst paste<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/stae_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/stae.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>stae<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/stela automix and capsule_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/stela automix and capsule.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>stela automix and capsule<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/stela primer_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/stela primer.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>stela primer<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/super etch_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/super etch.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>super etch<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/wave_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/wave.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>wave<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        \n            \n        <div class=\"vc_col-xs-12 pdf-download-item-col\">\n            <div class=\"pdf-download-item-wrapper\">\n                <div class=\"pdf-download-item\">\n                    <a class=\"jce_file\" title=\"\" href=\"\/pdfs\/sds\/en-ae\/zipbond_sdi_sds_en-ae.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">\n                                                    <img loading=\"lazy\" decoding=\"async\" src=\"\/pdfs\/icons\/zipbond.jpg\" width=\"25\" height=\"25\" \/>\n                                                <span>zipbond<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n\n                        <\/div>\n            <\/div>\n        \n            \n    \n            <\/div>\n        <\/div>\n     <!--\/\/This is to ensure there is no open div if the number of elements in pdfFiles is not a multiple of $rowItemsCount -->\n<\/div>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_row_inner el_class=&#8221;no-padding&#8221;][vc_column_inner width=&#8221;2\/3&#8243;][vc_column_text] Safety data sheets [\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][\/vc_column_inner][\/vc_row_inner][vc_row_inner el_class=&#8221;download_item&#8221;][vc_column_inner][vc_column_text][\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":14,"featured_media":0,"parent":8237,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/internal-page.php","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":"","_wp_rev_ctl_limit":""},"class_list":["post-8194","page","type-page","status-publish","hentry"],"acf":[],"ticketed":false,"_links":{"self":[{"href":"https:\/\/www.sdi.com.au\/en-ae\/wp-json\/wp\/v2\/pages\/8194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sdi.com.au\/en-ae\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.sdi.com.au\/en-ae\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.sdi.com.au\/en-ae\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sdi.com.au\/en-ae\/wp-json\/wp\/v2\/comments?post=8194"}],"version-history":[{"count":30,"href":"https:\/\/www.sdi.com.au\/en-ae\/wp-json\/wp\/v2\/pages\/8194\/revisions"}],"predecessor-version":[{"id":173380,"href":"https:\/\/www.sdi.com.au\/en-ae\/wp-json\/wp\/v2\/pages\/8194\/revisions\/173380"}],"up":[{"embeddable":true,"href":"https:\/\/www.sdi.com.au\/en-ae\/wp-json\/wp\/v2\/pages\/8237"}],"wp:attachment":[{"href":"https:\/\/www.sdi.com.au\/en-ae\/wp-json\/wp\/v2\/media?parent=8194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}